{"id":255,"date":"2015-01-12T17:41:34","date_gmt":"2015-01-12T17:41:34","guid":{"rendered":"http:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg"},"modified":"2015-01-12T17:41:34","modified_gmt":"2015-01-12T17:41:34","slug":"cartel-ambientaci-c3-b3n-pasillos-colegio","status":"inherit","type":"attachment","link":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/2021\/01\/29\/frases-celebres-por-la-paz\/cartel-ambientaci-c3-b3n-pasillos-colegio\/","title":{"rendered":"Cartel-ambientaci-C3-B3n-pasillos-colegio"},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-255","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartel-ambientaci-C3-B3n-pasillos-colegio - Biblioteca Escolar - Escolapios Granada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartel-ambientaci-C3-B3n-pasillos-colegio - Biblioteca Escolar - Escolapios Granada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Biblioteca Escolar - Escolapios Granada\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=1024%2C724&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/01\\\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg\",\"url\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/01\\\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg\",\"name\":\"Cartel-ambientaci-C3-B3n-pasillos-colegio - Biblioteca Escolar - Escolapios Granada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/#website\"},\"datePublished\":\"2015-01-12T17:41:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/01\\\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/01\\\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2014\\\/01\\\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FRASES C\u00c9LEBRES POR LA PAZ\",\"item\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/2021\\\/01\\\/29\\\/frases-celebres-por-la-paz\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cartel-ambientaci-C3-B3n-pasillos-colegio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/#website\",\"url\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/\",\"name\":\"Biblioteca Escolar - Escolapios Granada\",\"description\":\"Colegio Dulce Nombre de Mar\u00eda -PP.Escolapios- Granada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.granada.escolapiosemaus.org\\\/biblioteca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartel-ambientaci-C3-B3n-pasillos-colegio - Biblioteca Escolar - Escolapios Granada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg","og_locale":"es_ES","og_type":"article","og_title":"Cartel-ambientaci-C3-B3n-pasillos-colegio - Biblioteca Escolar - Escolapios Granada","og_url":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg","og_site_name":"Biblioteca Escolar - Escolapios Granada","og_image":[{"width":1024,"height":724,"url":"https:\/\/i1.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=1024%2C724&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg","url":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg","name":"Cartel-ambientaci-C3-B3n-pasillos-colegio - Biblioteca Escolar - Escolapios Granada","isPartOf":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/#website"},"datePublished":"2015-01-12T17:41:34+00:00","breadcrumb":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/"},{"@type":"ListItem","position":2,"name":"FRASES C\u00c9LEBRES POR LA PAZ","item":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/2021\/01\/29\/frases-celebres-por-la-paz\/"},{"@type":"ListItem","position":3,"name":"Cartel-ambientaci-C3-B3n-pasillos-colegio"}]},{"@type":"WebSite","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/#website","url":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/","name":"Biblioteca Escolar - Escolapios Granada","description":"Colegio Dulce Nombre de Mar\u00eda -PP.Escolapios- Granada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a8qkgn-47","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"212\" src=\"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=300%2C212&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?resize=200%2C141&amp;ssl=1 200w, https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?resize=424%2C300&amp;ssl=1 424w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"255\" data-permalink=\"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/2021\/01\/29\/frases-celebres-por-la-paz\/cartel-ambientaci-c3-b3n-pasillos-colegio\/\" data-orig-file=\"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=1024%2C724&amp;ssl=1\" data-orig-size=\"1024,724\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Cartel-ambientaci-C3-B3n-pasillos-colegio\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=600%2C424&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":724,"file":"2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg","sizes":{"thumbnail":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio-300x212.jpg","width":300,"height":212,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=300%2C212&ssl=1"},"large":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio-1024x724.jpg","width":1024,"height":724,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=600%2C424&ssl=1"},"rss-image":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio-200x141.jpg","width":200,"height":141,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=200%2C141&ssl=1"},"post-thumbnail":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio-1000x288.jpg"},"large-feature":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio-1000x288.jpg"},"small-feature":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio-424x300.jpg","width":424,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio-424x300.jpg"},"full":{"file":"Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=1024%2C724&ssl=1","width":1024,"height":724,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg?fit=1024%2C724&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":50,"source_url":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-content\/uploads\/sites\/18\/2014\/01\/Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg","filename":"Cartel-ambientaci-C3-B3n-pasillos-colegio.jpg","filesize":112054,"_links":{"self":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-json\/wp\/v2\/media\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-json\/wp\/v2\/comments?post=255"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":50,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/biblioteca\/wp-json\/wp\/v2\/posts\/50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}