{"id":435,"date":"2015-11-19T11:55:31","date_gmt":"2015-11-19T11:55:31","guid":{"rendered":"http:\/\/blogs.granada.escolapiosemaus.org\/ampa\/?p=435"},"modified":"2015-11-19T11:55:31","modified_gmt":"2015-11-19T11:55:31","slug":"el-3-de-diciembre-asamblea-general-del-ampa","status":"publish","type":"post","link":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/","title":{"rendered":"El 3 de diciembre, Asamblea General del Ampa"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>La\u00a0Asamblea General Ordinaria del Ampa de nuestro centro tendr\u00e1 lugar\u00a0para el pr\u00f3ximo jueves, 3 de diciembre de 2015, a las 18:00 horas en primera convocatoria y a las 18:30 horas en segunda convocatoria, en la SALA VERDE de las instalaciones del Colegio PP. Escolapios, con el siguiente<\/p>\n<p>ORDEN DEL D\u00cdA<\/p>\n<p>1. Lectura y Aprobaci\u00f3n, si procede, del Acta de la sesi\u00f3n anterior.<\/p>\n<p><a href=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-content\/uploads\/sites\/34\/2015\/11\/Acta-Asamblea-General-AMPA-11.12.2014.pdf\">Acta Asamblea General AMPA 11.12.2014<\/a><\/p>\n<p>2. Aprobaci\u00f3n, si procede, de la memoria de actividades, balance econ\u00f3mico y justificaci\u00f3n de gastos del curso 2014-2015.<\/p>\n<p><a href=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-content\/uploads\/sites\/34\/2015\/11\/Liquidaci\u00f3n-cierre-ejercicio-Curso-2014-15.pdf\">Liquidaci\u00f3n cierre ejercicio Curso 2014-15<\/a><\/p>\n<p>3. Plan de actividades y Presupuesto econ\u00f3mico para el curso 2015-2016. Su aprobaci\u00f3n, si procede.<\/p>\n<p><a href=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-content\/uploads\/sites\/34\/2015\/11\/Propuesta-de-Presupuestos-AMPA-2015-16.pdf\">Propuesta de Presupuestos AMPA 2015-16<\/a><\/p>\n<p>4. Comunicaci\u00f3n cambios en la Junta Directiva.<\/p>\n<p>5. Ruegos y preguntas.<\/p>\n<p><a href=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-content\/uploads\/sites\/34\/2015\/11\/Convocatoria-Asamblea-General-03.12.15.pdf\">Convocatoria Asamblea General 03.12.15<\/a><\/p>\n<\/div>\n<p>Esperamos contar con\u00a0el mayor n\u00famero posible de familias. Entre todos, haremos un cole mejor.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0Asamblea General Ordinaria del Ampa de nuestro centro tendr\u00e1 lugar\u00a0para el pr\u00f3ximo jueves, 3 de diciembre de 2015, a las 18:00 horas en primera convocatoria y a las 18:30 horas en segunda convocatoria, en la SALA VERDE de las instalaciones del Colegio PP. Escolapios, con el siguiente ORDEN DEL D\u00cdA 1. Lectura y Aprobaci\u00f3n, si [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-435","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El 3 de diciembre, Asamblea General del Ampa - Asociaci\u00f3n de Madres y Padres de Alumnos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 3 de diciembre, Asamblea General del Ampa - Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n<meta property=\"og:description\" content=\"La\u00a0Asamblea General Ordinaria del Ampa de nuestro centro tendr\u00e1 lugar\u00a0para el pr\u00f3ximo jueves, 3 de diciembre de 2015, a las 18:00 horas en primera convocatoria y a las 18:30 horas en segunda convocatoria, en la SALA VERDE de las instalaciones del Colegio PP. Escolapios, con el siguiente ORDEN DEL D\u00cdA 1. Lectura y Aprobaci\u00f3n, si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-19T11:55:31+00:00\" \/>\n<meta name=\"author\" content=\"Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/\"},\"author\":{\"name\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0\"},\"headline\":\"El 3 de diciembre, Asamblea General del Ampa\",\"datePublished\":\"2015-11-19T11:55:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/\"},\"wordCount\":150,\"commentCount\":0,\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/\",\"url\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/\",\"name\":\"El 3 de diciembre, Asamblea General del Ampa - Asociaci\u00f3n de Madres y Padres de Alumnos\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website\"},\"datePublished\":\"2015-11-19T11:55:31+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El 3 de diciembre, Asamblea General del Ampa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website\",\"url\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/\",\"name\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\",\"description\":\"Colegio Dulce Nombre de Mar\u00eda - Escolapios Granada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0\",\"name\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g\",\"caption\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\"},\"sameAs\":[\"https:\/\/blogs.granada.escolapiosemaus.org\"],\"url\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/author\/ampa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El 3 de diciembre, Asamblea General del Ampa - Asociaci\u00f3n de Madres y Padres de Alumnos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/","og_locale":"es_ES","og_type":"article","og_title":"El 3 de diciembre, Asamblea General del Ampa - Asociaci\u00f3n de Madres y Padres de Alumnos","og_description":"La\u00a0Asamblea General Ordinaria del Ampa de nuestro centro tendr\u00e1 lugar\u00a0para el pr\u00f3ximo jueves, 3 de diciembre de 2015, a las 18:00 horas en primera convocatoria y a las 18:30 horas en segunda convocatoria, en la SALA VERDE de las instalaciones del Colegio PP. Escolapios, con el siguiente ORDEN DEL D\u00cdA 1. Lectura y Aprobaci\u00f3n, si [&hellip;]","og_url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/","og_site_name":"Asociaci\u00f3n de Madres y Padres de Alumnos","article_published_time":"2015-11-19T11:55:31+00:00","author":"Asociaci\u00f3n de Madres y Padres de Alumnos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Asociaci\u00f3n de Madres y Padres de Alumnos","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#article","isPartOf":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/"},"author":{"name":"Asociaci\u00f3n de Madres y Padres de Alumnos","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0"},"headline":"El 3 de diciembre, Asamblea General del Ampa","datePublished":"2015-11-19T11:55:31+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/"},"wordCount":150,"commentCount":0,"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/","url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/","name":"El 3 de diciembre, Asamblea General del Ampa - Asociaci\u00f3n de Madres y Padres de Alumnos","isPartOf":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website"},"datePublished":"2015-11-19T11:55:31+00:00","author":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0"},"breadcrumb":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2015\/11\/19\/el-3-de-diciembre-asamblea-general-del-ampa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/"},{"@type":"ListItem","position":2,"name":"El 3 de diciembre, Asamblea General del Ampa"}]},{"@type":"WebSite","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website","url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/","name":"Asociaci\u00f3n de Madres y Padres de Alumnos","description":"Colegio Dulce Nombre de Mar\u00eda - Escolapios Granada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0","name":"Asociaci\u00f3n de Madres y Padres de Alumnos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g","caption":"Asociaci\u00f3n de Madres y Padres de Alumnos"},"sameAs":["https:\/\/blogs.granada.escolapiosemaus.org"],"url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/author\/ampa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5Ub4B-71","_links":{"self":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/posts\/435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/comments?post=435"}],"version-history":[{"count":3,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/posts\/435\/revisions"}],"predecessor-version":[{"id":442,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/posts\/435\/revisions\/442"}],"wp:attachment":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/media?parent=435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/categories?post=435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/tags?post=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}