{"id":178,"date":"2013-11-21T10:17:46","date_gmt":"2013-11-21T09:17:46","guid":{"rendered":"http:\/\/ampaescolapiosgranada.es\/?p=178"},"modified":"2013-11-21T10:17:46","modified_gmt":"2013-11-21T09:17:46","slug":"fiesta-de-calasanz","status":"publish","type":"post","link":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/","title":{"rendered":"FIESTA DE CALASANZ"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-179\" alt=\"Planning Fiesta San Jos\u00e9 de Calasanz\" src=\"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-content\/uploads\/sites\/34\/2013\/11\/planning-225x300.jpg 225w, https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-content\/uploads\/sites\/34\/2013\/11\/planning-150x200.jpg 150w, https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-content\/uploads\/sites\/34\/2013\/11\/planning.jpg 600w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>El pr\u00f3ximo<strong> viernes 29 de Noviembre<\/strong>, celebraremos en el cole la <strong>festividad de San Jos\u00e9 de Calasanz<\/strong>, y como es habitual en esta fiesta, es necesaria la implicaci\u00f3n y participaci\u00f3n de los padres en la preparaci\u00f3n de la fiesta, y lo que es m\u00e1s importante a\u00fan, la participaci\u00f3n en la propia fiesta con nuestra asistencia en el desayuno compartido con nuestros hijos, que tanta ilusi\u00f3n les hace.<\/p>\n<p>Los padres y madres delegados de cada clase coordinan la organizaci\u00f3n de la fiesta... os animamos a poneros en contacto con ellos para participar en la misma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo viernes 29 de Noviembre, celebraremos en el cole la festividad de San Jos\u00e9 de Calasanz, y como es habitual en esta fiesta, es necesaria la implicaci\u00f3n y participaci\u00f3n de los padres en la preparaci\u00f3n de la fiesta, y lo que es m\u00e1s importante a\u00fan, la participaci\u00f3n en la propia fiesta con nuestra asistencia [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,7],"tags":[14,17],"class_list":["post-178","post","type-post","status-publish","format-standard","hentry","category-calasanz","category-fiestas","tag-calasanz","tag-fiestas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FIESTA DE CALASANZ - Asociaci\u00f3n de Madres y Padres de Alumnos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIESTA DE CALASANZ - Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo viernes 29 de Noviembre, celebraremos en el cole la festividad de San Jos\u00e9 de Calasanz, y como es habitual en esta fiesta, es necesaria la implicaci\u00f3n y participaci\u00f3n de los padres en la preparaci\u00f3n de la fiesta, y lo que es m\u00e1s importante a\u00fan, la participaci\u00f3n en la propia fiesta con nuestra asistencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-21T09:17:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg\" \/>\n<meta name=\"author\" content=\"Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Asociaci\u00f3n de Madres y Padres de Alumnos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/\"},\"author\":{\"name\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0\"},\"headline\":\"FIESTA DE CALASANZ\",\"datePublished\":\"2013-11-21T09:17:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/\"},\"wordCount\":105,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg\",\"keywords\":[\"Calasanz\",\"Fiestas\"],\"articleSection\":[\"Calasanz\",\"Fiestas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/\",\"url\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/\",\"name\":\"FIESTA DE CALASANZ - Asociaci\u00f3n de Madres y Padres de Alumnos\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg\",\"datePublished\":\"2013-11-21T09:17:46+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage\",\"url\":\"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg\",\"contentUrl\":\"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIESTA DE CALASANZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website\",\"url\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/\",\"name\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\",\"description\":\"Colegio Dulce Nombre de Mar\u00eda - Escolapios Granada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0\",\"name\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g\",\"caption\":\"Asociaci\u00f3n de Madres y Padres de Alumnos\"},\"sameAs\":[\"https:\/\/blogs.granada.escolapiosemaus.org\"],\"url\":\"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/author\/ampa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIESTA DE CALASANZ - Asociaci\u00f3n de Madres y Padres de Alumnos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/","og_locale":"es_ES","og_type":"article","og_title":"FIESTA DE CALASANZ - Asociaci\u00f3n de Madres y Padres de Alumnos","og_description":"El pr\u00f3ximo viernes 29 de Noviembre, celebraremos en el cole la festividad de San Jos\u00e9 de Calasanz, y como es habitual en esta fiesta, es necesaria la implicaci\u00f3n y participaci\u00f3n de los padres en la preparaci\u00f3n de la fiesta, y lo que es m\u00e1s importante a\u00fan, la participaci\u00f3n en la propia fiesta con nuestra asistencia [&hellip;]","og_url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/","og_site_name":"Asociaci\u00f3n de Madres y Padres de Alumnos","article_published_time":"2013-11-21T09:17:46+00:00","og_image":[{"url":"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg","type":"","width":"","height":""}],"author":"Asociaci\u00f3n de Madres y Padres de Alumnos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Asociaci\u00f3n de Madres y Padres de Alumnos","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#article","isPartOf":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/"},"author":{"name":"Asociaci\u00f3n de Madres y Padres de Alumnos","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0"},"headline":"FIESTA DE CALASANZ","datePublished":"2013-11-21T09:17:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/"},"wordCount":105,"commentCount":0,"image":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage"},"thumbnailUrl":"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg","keywords":["Calasanz","Fiestas"],"articleSection":["Calasanz","Fiestas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/","url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/","name":"FIESTA DE CALASANZ - Asociaci\u00f3n de Madres y Padres de Alumnos","isPartOf":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage"},"image":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage"},"thumbnailUrl":"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg","datePublished":"2013-11-21T09:17:46+00:00","author":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0"},"breadcrumb":{"@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#primaryimage","url":"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg","contentUrl":"http:\/\/ampaescolapiosgranada.es\/wp-content\/uploads\/2013\/11\/planning-225x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/2013\/11\/21\/fiesta-de-calasanz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/"},{"@type":"ListItem","position":2,"name":"FIESTA DE CALASANZ"}]},{"@type":"WebSite","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#website","url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/","name":"Asociaci\u00f3n de Madres y Padres de Alumnos","description":"Colegio Dulce Nombre de Mar\u00eda - Escolapios Granada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/6e74f47fd4f2a6d36649beb508e8a2d0","name":"Asociaci\u00f3n de Madres y Padres de Alumnos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a512ecd4739f2e32dc739a5fe7eb95e8?s=96&d=mm&r=g","caption":"Asociaci\u00f3n de Madres y Padres de Alumnos"},"sameAs":["https:\/\/blogs.granada.escolapiosemaus.org"],"url":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/author\/ampa\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5Ub4B-2S","_links":{"self":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/posts\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/comments?post=178"}],"version-history":[{"count":0,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/posts\/178\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/media?parent=178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/categories?post=178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.granada.escolapiosemaus.org\/ampa\/wp-json\/wp\/v2\/tags?post=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}